{"id":41169,"date":"2026-02-17T16:32:12","date_gmt":"2026-02-17T15:32:12","guid":{"rendered":"https:\/\/piracharcoalov.wpenginepowered.com\/catalog\/uncategorized\/bbq-m150-2\/"},"modified":"2026-04-27T13:14:40","modified_gmt":"2026-04-27T11:14:40","slug":"bbq-m150","status":"publish","type":"product","link":"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/","title":{"rendered":"BBQ M150"},"content":{"rendered":"<p data-start=\"128\" data-end=\"414\">Il barbecue a carbone professionale per eccellenza, progettato per cucine esigenti specializzate in autentica cucina barbecue. La sua robusta costruzione, il design raffinato e l&#8217;elevata capacit\u00e0 produttiva rendono il BBQ-M80 un elemento essenziale per i ristoranti in cui la grigliata \u00e8 il fulcro del men\u00f9.<\/p>\n<p data-start=\"416\" data-end=\"573\">Installato in rinomati studi professionali, questo modello offre affidabilit\u00e0, potenza e un controllo preciso del calore per risultati costanti durante tutto il servizio.<\/p>\n<p data-start=\"575\" data-end=\"836\">Adatto alla cottura di ogni tipo di alimento \u2014 carne, pesce e verdure \u2014 il barbecue \u00e8 fornito con una griglia scanalata e pu\u00f2 essere adattato a diverse configurazioni, tra cui griglie a barra, griglie rotanti, spiedini e paellere per stili di cottura specifici.<\/p>\n<p data-start=\"838\" data-end=\"1040\" data-is-last-node=\"\" data-is-only-node=\"\">Dotata di un esclusivo sistema di piattaforma della tramoggia regolabile, consente un controllo preciso dell&#8217;intensit\u00e0 di cottura in qualsiasi momento, garantendo massima flessibilit\u00e0, prestazioni ed efficienza nell&#8217;uso professionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Produzione di carne all&#8217;ora = 80 kg<\/li>\n<li>Dotato di vassoio anteriore per la raccolta del grasso \u2013 previene fiamme e incendi<\/li>\n<li>Interno in ghisa e acciaio: struttura robusta, adatta solo ai professionisti.<\/li>\n<li>Questo barbecue \u00e8 dotato di un sistema per controllare l&#8217;intensit\u00e0 di cottura (il cuoco pu\u00f2 controllare la posizione della griglia della tramoggia).<\/li>\n<li>Camera di cottura con pareti completamente isolate.<\/li>\n<li>Utilizzabile con tutti i tipi di carbone<\/li>\n<li>Vassoio raccogli cenere<\/li>\n<li>Fornito con 4 ruote con freno. Molto facile da spostare.<\/li>\n<li>Fornito con 2 griglie in acciaio scanalate speciali, 1 pinza per carne + 1 attizzatoio.<\/li>\n<li>Sono disponibili anche altri tipi di griglie: griglie a barre, griglie in ghisa, griglie speciali per pentole&#8230;<\/li>\n<\/ul>\n<p>Lo speciale design della griglia scanalata impedisce alle fiamme di raggiungere il cibo.<br \/>\nSi prega di notare che tutti i barbecue a carbone, come gli altri elementi di una cucina professionale, devono essere posizionati sotto una cappa aspirante. Pira pu\u00f2 fornire un sistema di aspirazione per garantire la massima efficienza in ogni caso.<\/p>\n","protected":false},"featured_media":41141,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[419],"product_tag":[],"class_list":["post-41169","product","type-product","status-publish","has-post-thumbnail","product_cat-barbecues","pa_size-m150","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BBQ M150 - Pira Charcoal Ovens and Barbecues<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BBQ M150 - Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"og:description\" content=\"Produzione di carne all&#039;ora = 80 kg  Dotato di vassoio anteriore per la raccolta del grasso \u2013 previene fiamme e incendi  Interno in ghisa e acciaio: struttura robusta, adatta solo ai professionisti.  Questo barbecue \u00e8 dotato di un sistema per controllare l&#039;intensit\u00e0 di cottura (il cuoco pu\u00f2 controllare la posizione della griglia della tramoggia).  Camera di cottura con pareti completamente isolate.  Utilizzabile con tutti i tipi di carbone  Vassoio raccogli cenere  Fornito con 4 ruote con freno. Molto facile da spostare.  Fornito con 2 griglie in acciaio scanalate speciali, 1 pinza per carne + 1 attizzatoio.  Sono disponibili anche altri tipi di griglie: griglie a barre, griglie in ghisa, griglie speciali per pentole...  Lo speciale design della griglia scanalata impedisce alle fiamme di raggiungere il cibo. Si prega di notare che tutti i barbecue a carbone, come gli altri elementi di una cucina professionale, devono essere posizionati sotto una cappa aspirante. Pira pu\u00f2 fornire un sistema di aspirazione per garantire la massima efficienza in ogni caso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/\" \/>\n<meta property=\"og:site_name\" content=\"Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T11:14:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/160.000-BBQ-M150-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Grill_PiraOvens\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/barbecues\\\/bbq-m150\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/barbecues\\\/bbq-m150\\\/\",\"name\":\"BBQ M150 - Pira Charcoal Ovens and Barbecues\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/barbecues\\\/bbq-m150\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/barbecues\\\/bbq-m150\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/160.000-BBQ-M150-1.png\",\"datePublished\":\"2026-02-17T15:32:12+00:00\",\"dateModified\":\"2026-04-27T11:14:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/barbecues\\\/bbq-m150\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/barbecues\\\/bbq-m150\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/barbecues\\\/bbq-m150\\\/#primaryimage\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/160.000-BBQ-M150-1.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/160.000-BBQ-M150-1.png\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/barbecues\\\/bbq-m150\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/azienda-di-forni-a-carbone-pira\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BBQ M150\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"description\":\"Making charcoal ovens and barbecues since 1984.\",\"publisher\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\"},\"alternateName\":\"Pira Ovens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/piracharcoalovens.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Pira Charcoal Ovens and Barbecues\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Pira-Charcoal-Ovens\\\/274222069396877?fref=ts\",\"https:\\\/\\\/x.com\\\/Grill_PiraOvens\",\"https:\\\/\\\/www.instagram.com\\\/piraovens\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@pira_charcoal_ovens\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pira-charcoal-ovens-and-barbecues-s-l-\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCk_-TTJOHBVcGWsoz3hlSIg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BBQ M150 - Pira Charcoal Ovens and Barbecues","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/","og_locale":"it_IT","og_type":"article","og_title":"BBQ M150 - Pira Charcoal Ovens and Barbecues","og_description":"Produzione di carne all'ora = 80 kg  Dotato di vassoio anteriore per la raccolta del grasso \u2013 previene fiamme e incendi  Interno in ghisa e acciaio: struttura robusta, adatta solo ai professionisti.  Questo barbecue \u00e8 dotato di un sistema per controllare l'intensit\u00e0 di cottura (il cuoco pu\u00f2 controllare la posizione della griglia della tramoggia).  Camera di cottura con pareti completamente isolate.  Utilizzabile con tutti i tipi di carbone  Vassoio raccogli cenere  Fornito con 4 ruote con freno. Molto facile da spostare.  Fornito con 2 griglie in acciaio scanalate speciali, 1 pinza per carne + 1 attizzatoio.  Sono disponibili anche altri tipi di griglie: griglie a barre, griglie in ghisa, griglie speciali per pentole...  Lo speciale design della griglia scanalata impedisce alle fiamme di raggiungere il cibo. Si prega di notare che tutti i barbecue a carbone, come gli altri elementi di una cucina professionale, devono essere posizionati sotto una cappa aspirante. Pira pu\u00f2 fornire un sistema di aspirazione per garantire la massima efficienza in ogni caso.","og_url":"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/","og_site_name":"Pira Charcoal Ovens and Barbecues","article_publisher":"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","article_modified_time":"2026-04-27T11:14:40+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/160.000-BBQ-M150-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Grill_PiraOvens","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/","url":"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/","name":"BBQ M150 - Pira Charcoal Ovens and Barbecues","isPartOf":{"@id":"https:\/\/piracharcoalovens.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/#primaryimage"},"image":{"@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/#primaryimage"},"thumbnailUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/160.000-BBQ-M150-1.png","datePublished":"2026-02-17T15:32:12+00:00","dateModified":"2026-04-27T11:14:40+00:00","breadcrumb":{"@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/#primaryimage","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/160.000-BBQ-M150-1.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/160.000-BBQ-M150-1.png","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/barbecues\/bbq-m150\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/piracharcoalovens.com\/it\/azienda-di-forni-a-carbone-pira\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/piracharcoalovens.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"BBQ M150"}]},{"@type":"WebSite","@id":"https:\/\/piracharcoalovens.com\/#website","url":"https:\/\/piracharcoalovens.com\/","name":"Pira Charcoal Ovens and Barbecues","description":"Making charcoal ovens and barbecues since 1984.","publisher":{"@id":"https:\/\/piracharcoalovens.com\/#organization"},"alternateName":"Pira Ovens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/piracharcoalovens.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/piracharcoalovens.com\/#organization","name":"Pira Charcoal Ovens and Barbecues","url":"https:\/\/piracharcoalovens.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","width":512,"height":512,"caption":"Pira Charcoal Ovens and Barbecues"},"image":{"@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","https:\/\/x.com\/Grill_PiraOvens","https:\/\/www.instagram.com\/piraovens\/","https:\/\/www.tiktok.com\/@pira_charcoal_ovens","https:\/\/www.linkedin.com\/company\/pira-charcoal-ovens-and-barbecues-s-l-","https:\/\/www.youtube.com\/channel\/UCk_-TTJOHBVcGWsoz3hlSIg"]}]}},"_links":{"self":[{"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product\/41169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/comments?post=41169"}],"version-history":[{"count":0,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product\/41169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/media\/41141"}],"wp:attachment":[{"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/media?parent=41169"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product_brand?post=41169"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product_cat?post=41169"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product_tag?post=41169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}