{"id":40696,"date":"2026-02-24T17:40:52","date_gmt":"2026-02-24T16:40:52","guid":{"rendered":"https:\/\/piracharcoalov.wpenginepowered.com\/catalog\/uncategorized\/piastra-m80-m150\/"},"modified":"2026-02-24T17:40:52","modified_gmt":"2026-02-24T16:40:52","slug":"piastra-m80-m150","status":"publish","type":"product","link":"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/","title":{"rendered":"Piastra M80 \/ M150"},"content":{"rendered":"<p>La nostra piastra di cottura \u00e8 realizzata in acciaio inox spesso, completamente saldato e lucidato, e presenta un design elegante. Il suo spessore, unito alle barre trasversali sul lato inferiore, le conferisce eccezionale robustezza e durata, ideale per tutti i vostri barbecue. <\/p>\n<p>La particolare inclinazione della piastra convoglia il grasso verso il collettore principale e da l\u00ec verso il raccoglitore interno presente in tutti i forni a carbone Pira. Questo sistema previene la formazione eccessiva di odori e fumo, soprattutto durante la cottura di alimenti grassi come pancetta, petto d&#8217;anatra e salsicce. La piastra \u00e8 ideale anche per la cottura di piatti delicati come uova strapazzate, pesce e verdure, che solitamente vengono preparati su una piastra ma che ora possono essere cotti in un forno a carbone.  <\/p>\n<p>Il design sul lato sinistro del tavolo garantisce che non ci saranno residui sul tavolo, sar\u00e0 pi\u00f9 rigoroso degli standard alimentari e render\u00e0 la cottura facile e veloce.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nostra piastra di cottura \u00e8 realizzata in acciaio inox spesso, completamente saldato e lucidato, e presenta un design elegante. Il suo spessore, unito alle barre trasversali sul lato inferiore, le conferisce eccezionale robustezza e durata, ideale per tutti i vostri barbecue. La particolare inclinazione della piastra convoglia il grasso verso il collettore principale e [&hellip;]<\/p>\n","protected":false},"featured_media":45771,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[418],"product_tag":[],"class_list":["post-40696","product","type-product","status-publish","has-post-thumbnail","product_cat-accessori","pa_accessory-type-piastra","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piastra M80 \/ M150 - Pira Charcoal Ovens and Barbecues<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piastra M80 \/ M150 - Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"og:description\" content=\"La nostra piastra di cottura \u00e8 realizzata in acciaio inox spesso, completamente saldato e lucidato, e presenta un design elegante. Il suo spessore, unito alle barre trasversali sul lato inferiore, le conferisce eccezionale robustezza e durata, ideale per tutti i vostri barbecue. La particolare inclinazione della piastra convoglia il grasso verso il collettore principale e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/\" \/>\n<meta property=\"og:site_name\" content=\"Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts\" \/>\n<meta property=\"og:image\" content=\"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/901.224-Half-Griddle-M80-M150-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Grill_PiraOvens\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/accessori\\\/piastra-m80-m150\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/accessori\\\/piastra-m80-m150\\\/\",\"name\":\"Piastra M80 \\\/ M150 - Pira Charcoal Ovens and Barbecues\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/accessori\\\/piastra-m80-m150\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/accessori\\\/piastra-m80-m150\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/901.224-Half-Griddle-M80-M150-1.webp\",\"datePublished\":\"2026-02-24T16:40:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/accessori\\\/piastra-m80-m150\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/accessori\\\/piastra-m80-m150\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/accessori\\\/piastra-m80-m150\\\/#primaryimage\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/901.224-Half-Griddle-M80-M150-1.webp\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/901.224-Half-Griddle-M80-M150-1.webp\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/catalogo\\\/accessori\\\/piastra-m80-m150\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/azienda-di-forni-a-carbone-pira\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Piastra M80 \\\/ M150\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"description\":\"Making charcoal ovens and barbecues since 1984.\",\"publisher\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\"},\"alternateName\":\"Pira Ovens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/piracharcoalovens.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Pira Charcoal Ovens and Barbecues\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Pira-Charcoal-Ovens\\\/274222069396877?fref=ts\",\"https:\\\/\\\/x.com\\\/Grill_PiraOvens\",\"https:\\\/\\\/www.instagram.com\\\/piraovens\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@pira_charcoal_ovens\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pira-charcoal-ovens-and-barbecues-s-l-\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCk_-TTJOHBVcGWsoz3hlSIg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piastra M80 \/ M150 - Pira Charcoal Ovens and Barbecues","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/","og_locale":"it_IT","og_type":"article","og_title":"Piastra M80 \/ M150 - Pira Charcoal Ovens and Barbecues","og_description":"La nostra piastra di cottura \u00e8 realizzata in acciaio inox spesso, completamente saldato e lucidato, e presenta un design elegante. Il suo spessore, unito alle barre trasversali sul lato inferiore, le conferisce eccezionale robustezza e durata, ideale per tutti i vostri barbecue. La particolare inclinazione della piastra convoglia il grasso verso il collettore principale e [&hellip;]","og_url":"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/","og_site_name":"Pira Charcoal Ovens and Barbecues","article_publisher":"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","og_image":[{"width":1280,"height":1280,"url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/901.224-Half-Griddle-M80-M150-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@Grill_PiraOvens","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/","url":"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/","name":"Piastra M80 \/ M150 - Pira Charcoal Ovens and Barbecues","isPartOf":{"@id":"https:\/\/piracharcoalovens.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/#primaryimage"},"image":{"@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/#primaryimage"},"thumbnailUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/901.224-Half-Griddle-M80-M150-1.webp","datePublished":"2026-02-24T16:40:52+00:00","breadcrumb":{"@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/#primaryimage","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/901.224-Half-Griddle-M80-M150-1.webp","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/901.224-Half-Griddle-M80-M150-1.webp","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/piracharcoalovens.com\/it\/catalogo\/accessori\/piastra-m80-m150\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/piracharcoalovens.com\/it\/azienda-di-forni-a-carbone-pira\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/piracharcoalovens.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Piastra M80 \/ M150"}]},{"@type":"WebSite","@id":"https:\/\/piracharcoalovens.com\/#website","url":"https:\/\/piracharcoalovens.com\/","name":"Pira Charcoal Ovens and Barbecues","description":"Making charcoal ovens and barbecues since 1984.","publisher":{"@id":"https:\/\/piracharcoalovens.com\/#organization"},"alternateName":"Pira Ovens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/piracharcoalovens.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/piracharcoalovens.com\/#organization","name":"Pira Charcoal Ovens and Barbecues","url":"https:\/\/piracharcoalovens.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","width":512,"height":512,"caption":"Pira Charcoal Ovens and Barbecues"},"image":{"@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","https:\/\/x.com\/Grill_PiraOvens","https:\/\/www.instagram.com\/piraovens\/","https:\/\/www.tiktok.com\/@pira_charcoal_ovens","https:\/\/www.linkedin.com\/company\/pira-charcoal-ovens-and-barbecues-s-l-","https:\/\/www.youtube.com\/channel\/UCk_-TTJOHBVcGWsoz3hlSIg"]}]}},"_links":{"self":[{"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product\/40696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/comments?post=40696"}],"version-history":[{"count":0,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product\/40696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/media\/45771"}],"wp:attachment":[{"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/media?parent=40696"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product_brand?post=40696"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product_cat?post=40696"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/it\/wp-json\/wp\/v2\/product_tag?post=40696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}