{"id":33746,"date":"2026-03-04T12:14:31","date_gmt":"2026-03-04T11:14:31","guid":{"rendered":"https:\/\/piracharcoalov.wpenginepowered.com\/catalog\/sin%20categor\u00eda\/bandeja-gn-1-1-2-5\/"},"modified":"2026-04-15T18:09:11","modified_gmt":"2026-04-15T16:09:11","slug":"bandeja-gn-1-1-2-5","status":"publish","type":"product","link":"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/","title":{"rendered":"Bandeja GN 1\/1 2.5"},"content":{"rendered":"<p>En Pira Charcoal Ovens, dise\u00f1amos utensilios de cocina espec\u00edficamente desarrollados para un rendimiento \u00f3ptimo en hornos de carb\u00f3n. La bandeja Gastronorm GN 1\/1 de aluminio fundido forma parte de nuestra l\u00ednea de utensilios de cocina profesionales, elaborada artesanalmente pieza a pieza mediante tecnolog\u00eda avanzada de fundici\u00f3n por gravedad. <\/p>\n<p>Este proceso crea una estructura molecular ultrarresistente capaz de soportar temperaturas muy elevadas sin deformarse. Combinado con la excelente conductividad t\u00e9rmica del aluminio fundido, garantiza una distribuci\u00f3n del calor r\u00e1pida y uniforme para obtener resultados de cocci\u00f3n consistentes. <\/p>\n<p>El interior cuenta con un revestimiento antiadherente de alta calidad que garantiza durabilidad y facilita la cocci\u00f3n, mientras que la base rectificada con diamante maximiza la conducci\u00f3n del calor.<\/p>\n<p>Dise\u00f1ada para cocinas profesionales exigentes, la bater\u00eda de cocina Pira ayuda a realzar el aut\u00e9ntico sabor de la cocci\u00f3n al carb\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Pira Charcoal Ovens, dise\u00f1amos utensilios de cocina espec\u00edficamente desarrollados para un rendimiento \u00f3ptimo en hornos de carb\u00f3n. La bandeja Gastronorm GN 1\/1 de aluminio fundido forma parte de nuestra l\u00ednea de utensilios de cocina profesionales, elaborada artesanalmente pieza a pieza mediante tecnolog\u00eda avanzada de fundici\u00f3n por gravedad. Este proceso crea una estructura molecular ultrarresistente [&hellip;]<\/p>\n","protected":false},"featured_media":44702,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[403],"product_tag":[],"class_list":["post-33746","product","type-product","status-publish","has-post-thumbnail","product_cat-otros-productos","pa_product-type-menaje-de-aluminio","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bandeja GN 1\/1 2.5 - Pira Charcoal Ovens and Barbecues<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bandeja GN 1\/1 2.5 - Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"og:description\" content=\"En Pira Charcoal Ovens, dise\u00f1amos utensilios de cocina espec\u00edficamente desarrollados para un rendimiento \u00f3ptimo en hornos de carb\u00f3n. La bandeja Gastronorm GN 1\/1 de aluminio fundido forma parte de nuestra l\u00ednea de utensilios de cocina profesionales, elaborada artesanalmente pieza a pieza mediante tecnolog\u00eda avanzada de fundici\u00f3n por gravedad. Este proceso crea una estructura molecular ultrarresistente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T16:09:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/931.125-Tray-GN-1.1-height-2.5-cm-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Grill_PiraOvens\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/otros-productos\\\/bandeja-gn-1-1-2-5\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/otros-productos\\\/bandeja-gn-1-1-2-5\\\/\",\"name\":\"Bandeja GN 1\\\/1 2.5 - Pira Charcoal Ovens and Barbecues\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/otros-productos\\\/bandeja-gn-1-1-2-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/otros-productos\\\/bandeja-gn-1-1-2-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/931.125-Tray-GN-1.1-height-2.5-cm-2.jpg\",\"datePublished\":\"2026-03-04T11:14:31+00:00\",\"dateModified\":\"2026-04-15T16:09:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/otros-productos\\\/bandeja-gn-1-1-2-5\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/otros-productos\\\/bandeja-gn-1-1-2-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/otros-productos\\\/bandeja-gn-1-1-2-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/931.125-Tray-GN-1.1-height-2.5-cm-2.jpg\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/931.125-Tray-GN-1.1-height-2.5-cm-2.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/otros-productos\\\/bandeja-gn-1-1-2-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/pira-charcoal-ovens-company\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bandeja GN 1\\\/1 2.5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"description\":\"Making charcoal ovens and barbecues since 1984.\",\"publisher\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\"},\"alternateName\":\"Pira Ovens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/piracharcoalovens.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Pira Charcoal Ovens and Barbecues\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Pira-Charcoal-Ovens\\\/274222069396877?fref=ts\",\"https:\\\/\\\/x.com\\\/Grill_PiraOvens\",\"https:\\\/\\\/www.instagram.com\\\/piraovens\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@pira_charcoal_ovens\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pira-charcoal-ovens-and-barbecues-s-l-\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCk_-TTJOHBVcGWsoz3hlSIg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bandeja GN 1\/1 2.5 - Pira Charcoal Ovens and Barbecues","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/","og_locale":"es_ES","og_type":"article","og_title":"Bandeja GN 1\/1 2.5 - Pira Charcoal Ovens and Barbecues","og_description":"En Pira Charcoal Ovens, dise\u00f1amos utensilios de cocina espec\u00edficamente desarrollados para un rendimiento \u00f3ptimo en hornos de carb\u00f3n. La bandeja Gastronorm GN 1\/1 de aluminio fundido forma parte de nuestra l\u00ednea de utensilios de cocina profesionales, elaborada artesanalmente pieza a pieza mediante tecnolog\u00eda avanzada de fundici\u00f3n por gravedad. Este proceso crea una estructura molecular ultrarresistente [&hellip;]","og_url":"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/","og_site_name":"Pira Charcoal Ovens and Barbecues","article_publisher":"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","article_modified_time":"2026-04-15T16:09:11+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/931.125-Tray-GN-1.1-height-2.5-cm-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Grill_PiraOvens","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/","url":"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/","name":"Bandeja GN 1\/1 2.5 - Pira Charcoal Ovens and Barbecues","isPartOf":{"@id":"https:\/\/piracharcoalovens.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/#primaryimage"},"image":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/#primaryimage"},"thumbnailUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/931.125-Tray-GN-1.1-height-2.5-cm-2.jpg","datePublished":"2026-03-04T11:14:31+00:00","dateModified":"2026-04-15T16:09:11+00:00","breadcrumb":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/#primaryimage","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/931.125-Tray-GN-1.1-height-2.5-cm-2.jpg","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/931.125-Tray-GN-1.1-height-2.5-cm-2.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/otros-productos\/bandeja-gn-1-1-2-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/piracharcoalovens.com\/es\/pira-charcoal-ovens-company\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/piracharcoalovens.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Bandeja GN 1\/1 2.5"}]},{"@type":"WebSite","@id":"https:\/\/piracharcoalovens.com\/#website","url":"https:\/\/piracharcoalovens.com\/","name":"Pira Charcoal Ovens and Barbecues","description":"Making charcoal ovens and barbecues since 1984.","publisher":{"@id":"https:\/\/piracharcoalovens.com\/#organization"},"alternateName":"Pira Ovens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/piracharcoalovens.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/piracharcoalovens.com\/#organization","name":"Pira Charcoal Ovens and Barbecues","url":"https:\/\/piracharcoalovens.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","width":512,"height":512,"caption":"Pira Charcoal Ovens and Barbecues"},"image":{"@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","https:\/\/x.com\/Grill_PiraOvens","https:\/\/www.instagram.com\/piraovens\/","https:\/\/www.tiktok.com\/@pira_charcoal_ovens","https:\/\/www.linkedin.com\/company\/pira-charcoal-ovens-and-barbecues-s-l-","https:\/\/www.youtube.com\/channel\/UCk_-TTJOHBVcGWsoz3hlSIg"]}]}},"_links":{"self":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product\/33746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/comments?post=33746"}],"version-history":[{"count":0,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product\/33746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/media\/44702"}],"wp:attachment":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/media?parent=33746"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_brand?post=33746"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_cat?post=33746"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_tag?post=33746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}