{"id":33688,"date":"2026-02-24T17:40:52","date_gmt":"2026-02-24T16:40:52","guid":{"rendered":"https:\/\/piracharcoalov.wpenginepowered.com\/catalog\/sin%20categor\u00eda\/plancha-m80-m150\/"},"modified":"2026-04-15T18:39:34","modified_gmt":"2026-04-15T16:39:34","slug":"plancha-m80-m150","status":"publish","type":"product","link":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/","title":{"rendered":"Plancha M80\/M150"},"content":{"rendered":"<p>Nuestra plancha est\u00e1 fabricada en acero inoxidable grueso, totalmente soldada, pulida y con un dise\u00f1o atractivo. Su grosor, junto con los refuerzos transversales en la parte inferior, ofrece una resistencia y durabilidad inigualables, ideal para cualquier barbacoa. <\/p>\n<p>La inclinaci\u00f3n especial de la placa dirige los aceites al colector general y luego al colector interno de grasa en todos los hornos de carb\u00f3n Pira. Esta caracter\u00edstica ayuda a evitar olores y humo excesivo, especialmente al cocinar alimentos grasos como tocino, magret de pato y salchichas. La placa tambi\u00e9n es perfecta para cocinar alimentos delicados como huevos revueltos, pescado y verduras, que tradicionalmente se preparan en una plancha, pero que ahora se pueden cocinar en un horno de carb\u00f3n.  <\/p>\n<p>El dise\u00f1o sin esquinas del plato garantiza que no se acumulen restos de comida, cumpliendo con los m\u00e1s altos est\u00e1ndares de seguridad alimentaria a la vez que facilita y agiliza la limpieza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra plancha est\u00e1 fabricada en acero inoxidable grueso, totalmente soldada, pulida y con un dise\u00f1o atractivo. Su grosor, junto con los refuerzos transversales en la parte inferior, ofrece una resistencia y durabilidad inigualables, ideal para cualquier barbacoa. La inclinaci\u00f3n especial de la placa dirige los aceites al colector general y luego al colector interno de [&hellip;]<\/p>\n","protected":false},"featured_media":45769,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[397],"product_tag":[],"class_list":["post-33688","product","type-product","status-publish","has-post-thumbnail","product_cat-accesorios","pa_accessory-type-planchas","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plancha M80\/M150 - Pira Charcoal Ovens and Barbecues<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plancha M80\/M150 - Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"og:description\" content=\"Nuestra plancha est\u00e1 fabricada en acero inoxidable grueso, totalmente soldada, pulida y con un dise\u00f1o atractivo. Su grosor, junto con los refuerzos transversales en la parte inferior, ofrece una resistencia y durabilidad inigualables, ideal para cualquier barbacoa. La inclinaci\u00f3n especial de la placa dirige los aceites al colector general y luego al colector interno de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/\" \/>\n<meta property=\"og:site_name\" content=\"Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T16:39:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/901.024-Griddle-M80-M150-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Grill_PiraOvens\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/plancha-m80-m150\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/plancha-m80-m150\\\/\",\"name\":\"Plancha M80\\\/M150 - Pira Charcoal Ovens and Barbecues\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/plancha-m80-m150\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/plancha-m80-m150\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/901.224-Half-Griddle-M80-M150-1.webp\",\"datePublished\":\"2026-02-24T16:40:52+00:00\",\"dateModified\":\"2026-04-15T16:39:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/plancha-m80-m150\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/plancha-m80-m150\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/plancha-m80-m150\\\/#primaryimage\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/901.224-Half-Griddle-M80-M150-1.webp\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/901.224-Half-Griddle-M80-M150-1.webp\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/plancha-m80-m150\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/pira-charcoal-ovens-company\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plancha M80\\\/M150\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"description\":\"Making charcoal ovens and barbecues since 1984.\",\"publisher\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\"},\"alternateName\":\"Pira Ovens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/piracharcoalovens.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Pira Charcoal Ovens and Barbecues\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Pira-Charcoal-Ovens\\\/274222069396877?fref=ts\",\"https:\\\/\\\/x.com\\\/Grill_PiraOvens\",\"https:\\\/\\\/www.instagram.com\\\/piraovens\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@pira_charcoal_ovens\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pira-charcoal-ovens-and-barbecues-s-l-\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCk_-TTJOHBVcGWsoz3hlSIg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plancha M80\/M150 - Pira Charcoal Ovens and Barbecues","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/","og_locale":"es_ES","og_type":"article","og_title":"Plancha M80\/M150 - Pira Charcoal Ovens and Barbecues","og_description":"Nuestra plancha est\u00e1 fabricada en acero inoxidable grueso, totalmente soldada, pulida y con un dise\u00f1o atractivo. Su grosor, junto con los refuerzos transversales en la parte inferior, ofrece una resistencia y durabilidad inigualables, ideal para cualquier barbacoa. La inclinaci\u00f3n especial de la placa dirige los aceites al colector general y luego al colector interno de [&hellip;]","og_url":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/","og_site_name":"Pira Charcoal Ovens and Barbecues","article_publisher":"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","article_modified_time":"2026-04-15T16:39:34+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/901.024-Griddle-M80-M150-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Grill_PiraOvens","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/","url":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/","name":"Plancha M80\/M150 - Pira Charcoal Ovens and Barbecues","isPartOf":{"@id":"https:\/\/piracharcoalovens.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/#primaryimage"},"image":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/#primaryimage"},"thumbnailUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/901.224-Half-Griddle-M80-M150-1.webp","datePublished":"2026-02-24T16:40:52+00:00","dateModified":"2026-04-15T16:39:34+00:00","breadcrumb":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/#primaryimage","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/901.224-Half-Griddle-M80-M150-1.webp","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/901.224-Half-Griddle-M80-M150-1.webp","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/plancha-m80-m150\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/piracharcoalovens.com\/es\/pira-charcoal-ovens-company\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/piracharcoalovens.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Plancha M80\/M150"}]},{"@type":"WebSite","@id":"https:\/\/piracharcoalovens.com\/#website","url":"https:\/\/piracharcoalovens.com\/","name":"Pira Charcoal Ovens and Barbecues","description":"Making charcoal ovens and barbecues since 1984.","publisher":{"@id":"https:\/\/piracharcoalovens.com\/#organization"},"alternateName":"Pira Ovens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/piracharcoalovens.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/piracharcoalovens.com\/#organization","name":"Pira Charcoal Ovens and Barbecues","url":"https:\/\/piracharcoalovens.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","width":512,"height":512,"caption":"Pira Charcoal Ovens and Barbecues"},"image":{"@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","https:\/\/x.com\/Grill_PiraOvens","https:\/\/www.instagram.com\/piraovens\/","https:\/\/www.tiktok.com\/@pira_charcoal_ovens","https:\/\/www.linkedin.com\/company\/pira-charcoal-ovens-and-barbecues-s-l-","https:\/\/www.youtube.com\/channel\/UCk_-TTJOHBVcGWsoz3hlSIg"]}]}},"_links":{"self":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product\/33688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/comments?post=33688"}],"version-history":[{"count":0,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product\/33688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/media\/45769"}],"wp:attachment":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/media?parent=33688"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_brand?post=33688"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_cat?post=33688"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_tag?post=33688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}