{"id":33609,"date":"2026-03-03T09:42:17","date_gmt":"2026-03-03T08:42:17","guid":{"rendered":"https:\/\/piracharcoalov.wpenginepowered.com\/catalog\/sin%20categor\u00eda\/mesa-silver-160-esp\/"},"modified":"2026-04-15T18:37:52","modified_gmt":"2026-04-15T16:37:52","slug":"mesa-silver-160-esp","status":"publish","type":"product","link":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/","title":{"rendered":"Mesa Silver 160 ESP"},"content":{"rendered":"<p>Las mesas Pira est\u00e1n dise\u00f1adas para que los espeteros puedan salir f\u00e1cilmente de la cocina y cocinar frente al p\u00fablico. La mesa frontal ofrece espacio para colocar ollas y alimentos, manteniendo los utensilios ocultos a la vista, lo que permite al p\u00fablico ver al chef en acci\u00f3n. <\/p>\n<p>Con un dise\u00f1o moderno y atractivo, estas mesas est\u00e1n dise\u00f1adas para el uso diario en cocinas profesionales y son capaces de soportar el desgaste. No presentan puntos ciegos, lo que facilita la limpieza y evita la acumulaci\u00f3n de carb\u00f3n en la zona de almacenamiento. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las mesas Pira est\u00e1n dise\u00f1adas para que los espeteros puedan salir f\u00e1cilmente de la cocina y cocinar frente al p\u00fablico. La mesa frontal ofrece espacio para colocar ollas y alimentos, manteniendo los utensilios ocultos a la vista, lo que permite al p\u00fablico ver al chef en acci\u00f3n. Con un dise\u00f1o moderno y atractivo, estas mesas [&hellip;]<\/p>\n","protected":false},"featured_media":2622,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[397],"product_tag":[],"class_list":["post-33609","product","type-product","status-publish","has-post-thumbnail","product_cat-accesorios","pa_accessory-type-mesa-carbonera","pa_accessory-type-mesas","pa_product-type-espeteros","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesa Silver 160 ESP - Pira Charcoal Ovens and Barbecues<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesa Silver 160 ESP - Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"og:description\" content=\"Las mesas Pira est\u00e1n dise\u00f1adas para que los espeteros puedan salir f\u00e1cilmente de la cocina y cocinar frente al p\u00fablico. La mesa frontal ofrece espacio para colocar ollas y alimentos, manteniendo los utensilios ocultos a la vista, lo que permite al p\u00fablico ver al chef en acci\u00f3n. Con un dise\u00f1o moderno y atractivo, estas mesas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/\" \/>\n<meta property=\"og:site_name\" content=\"Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T16:37:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/773.536-Table-160-Silver.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Grill_PiraOvens\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/mesa-silver-160-esp\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/mesa-silver-160-esp\\\/\",\"name\":\"Mesa Silver 160 ESP - Pira Charcoal Ovens and Barbecues\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/mesa-silver-160-esp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/mesa-silver-160-esp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/773.536-Table-160-Silver.png\",\"datePublished\":\"2026-03-03T08:42:17+00:00\",\"dateModified\":\"2026-04-15T16:37:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/mesa-silver-160-esp\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/mesa-silver-160-esp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/mesa-silver-160-esp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/773.536-Table-160-Silver.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/773.536-Table-160-Silver.png\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/accesorios\\\/mesa-silver-160-esp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/pira-charcoal-ovens-company\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mesa Silver 160 ESP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"description\":\"Making charcoal ovens and barbecues since 1984.\",\"publisher\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\"},\"alternateName\":\"Pira Ovens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/piracharcoalovens.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Pira Charcoal Ovens and Barbecues\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Pira-Charcoal-Ovens\\\/274222069396877?fref=ts\",\"https:\\\/\\\/x.com\\\/Grill_PiraOvens\",\"https:\\\/\\\/www.instagram.com\\\/piraovens\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@pira_charcoal_ovens\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pira-charcoal-ovens-and-barbecues-s-l-\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCk_-TTJOHBVcGWsoz3hlSIg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesa Silver 160 ESP - Pira Charcoal Ovens and Barbecues","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/","og_locale":"es_ES","og_type":"article","og_title":"Mesa Silver 160 ESP - Pira Charcoal Ovens and Barbecues","og_description":"Las mesas Pira est\u00e1n dise\u00f1adas para que los espeteros puedan salir f\u00e1cilmente de la cocina y cocinar frente al p\u00fablico. La mesa frontal ofrece espacio para colocar ollas y alimentos, manteniendo los utensilios ocultos a la vista, lo que permite al p\u00fablico ver al chef en acci\u00f3n. Con un dise\u00f1o moderno y atractivo, estas mesas [&hellip;]","og_url":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/","og_site_name":"Pira Charcoal Ovens and Barbecues","article_publisher":"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","article_modified_time":"2026-04-15T16:37:52+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/773.536-Table-160-Silver.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Grill_PiraOvens","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/","url":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/","name":"Mesa Silver 160 ESP - Pira Charcoal Ovens and Barbecues","isPartOf":{"@id":"https:\/\/piracharcoalovens.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/#primaryimage"},"image":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/#primaryimage"},"thumbnailUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/773.536-Table-160-Silver.png","datePublished":"2026-03-03T08:42:17+00:00","dateModified":"2026-04-15T16:37:52+00:00","breadcrumb":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/#primaryimage","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/773.536-Table-160-Silver.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/773.536-Table-160-Silver.png","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/accesorios\/mesa-silver-160-esp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/piracharcoalovens.com\/es\/pira-charcoal-ovens-company\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/piracharcoalovens.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Mesa Silver 160 ESP"}]},{"@type":"WebSite","@id":"https:\/\/piracharcoalovens.com\/#website","url":"https:\/\/piracharcoalovens.com\/","name":"Pira Charcoal Ovens and Barbecues","description":"Making charcoal ovens and barbecues since 1984.","publisher":{"@id":"https:\/\/piracharcoalovens.com\/#organization"},"alternateName":"Pira Ovens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/piracharcoalovens.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/piracharcoalovens.com\/#organization","name":"Pira Charcoal Ovens and Barbecues","url":"https:\/\/piracharcoalovens.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","width":512,"height":512,"caption":"Pira Charcoal Ovens and Barbecues"},"image":{"@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","https:\/\/x.com\/Grill_PiraOvens","https:\/\/www.instagram.com\/piraovens\/","https:\/\/www.tiktok.com\/@pira_charcoal_ovens","https:\/\/www.linkedin.com\/company\/pira-charcoal-ovens-and-barbecues-s-l-","https:\/\/www.youtube.com\/channel\/UCk_-TTJOHBVcGWsoz3hlSIg"]}]}},"_links":{"self":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product\/33609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/comments?post=33609"}],"version-history":[{"count":0,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product\/33609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/media\/2622"}],"wp:attachment":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/media?parent=33609"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_brand?post=33609"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_cat?post=33609"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_tag?post=33609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}