{"id":33439,"date":"2026-02-17T16:40:55","date_gmt":"2026-02-17T15:40:55","guid":{"rendered":"https:\/\/piracharcoalov.wpenginepowered.com\/catalog\/sin%20categor\u00eda\/esp-160-lux-basic\/"},"modified":"2026-04-16T12:52:50","modified_gmt":"2026-04-16T10:52:50","slug":"esp-160-lux-basic","status":"publish","type":"product","link":"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/","title":{"rendered":"ESP 160 Lux Basic"},"content":{"rendered":"<p data-start=\"138\" data-end=\"411\">Una nueva y original l\u00ednea de barbacoas de sobremesa se suma al cat\u00e1logo de Pira, presentando el concepto Robata Shashlik para cocinas profesionales. Dise\u00f1ada para su uso sobre la encimera, permite a los chefs cocinar directamente frente a los comensales, convirtiendo la parrillada con carb\u00f3n en una experiencia culinaria en vivo. <\/p>\n<p data-start=\"413\" data-end=\"694\">Inspirada en las parrillas robata tradicionales japonesas, esta barbacoa combina diversos estilos de cocci\u00f3n, como brochetas, shashlik, brochetas y espetos. La bandeja recogegrasa sostiene las brochetas de acero inoxidable en un \u00e1ngulo de 45\u00ba sobre las brasas, lo que garantiza una posici\u00f3n estable y una cocci\u00f3n precisa. <\/p>\n<p data-start=\"696\" data-end=\"958\">Equipada con una columna de ajuste de altura multiposici\u00f3n, la Robata permite un control preciso del fuego, mientras que la bandeja superior mantiene las brochetas calientes o atempera los ingredientes antes de cocinarlos. La barra de soporte ajustable se adapta a diferentes tama\u00f1os de brochetas para una m\u00e1xima flexibilidad. <\/p>\n<p data-start=\"960\" data-end=\"1171\" data-is-last-node=\"\" data-is-only-node=\"\">Entre los accesorios opcionales se incluyen rejillas ranuradas y de varillas, as\u00ed como una mesa de soporte de acero inoxidable con ruedas, estantes y puerta, que proporciona movilidad, almacenamiento y una mayor funcionalidad en entornos profesionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Columna para sostener las rejas<\/li>\n<li>Estante superior para mantener calientes las brochetas o los platos.<\/li>\n<li>3 tipos de parrillas: de varillas, ranuradas y con soporte ajustable para brochetas.<\/li>\n<li>Colector de grasa Inox con soporte para \u00abespetos\u00bb<\/li>\n<li>Interior de ladrillo refractario<\/li>\n<li>Tolva de carb\u00f3n de hierro fundido<\/li>\n<li>Cenicero<\/li>\n<li>Patas ajustables de hierro<\/li>\n<li>Atizador<\/li>\n<li>Pinzas<\/li>\n<\/ul>\n","protected":false},"featured_media":33440,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[401],"product_tag":[],"class_list":["post-33439","product","type-product","status-publish","has-post-thumbnail","product_cat-espeteros","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESP 160 Lux Basic - Pira Charcoal Ovens and Barbecues<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESP 160 Lux Basic - Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"og:description\" content=\"Columna para sostener las rejas  Estante superior para mantener calientes las brochetas o los platos.  3 tipos de parrillas: de varillas, ranuradas y con soporte ajustable para brochetas.  Colector de grasa Inox con soporte para &quot;espetos&quot;  Interior de ladrillo refractario  Tolva de carb\u00f3n de hierro fundido  Cenicero  Patas ajustables de hierro  Atizador  Pinzas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/\" \/>\n<meta property=\"og:site_name\" content=\"Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T10:52:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/353.500-ESP-160-Lux-Basic.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Grill_PiraOvens\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/espeteros\\\/esp-160-lux-basic\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/espeteros\\\/esp-160-lux-basic\\\/\",\"name\":\"ESP 160 Lux Basic - Pira Charcoal Ovens and Barbecues\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/espeteros\\\/esp-160-lux-basic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/espeteros\\\/esp-160-lux-basic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/353.500-ESP-160-Lux-Basic.png\",\"datePublished\":\"2026-02-17T15:40:55+00:00\",\"dateModified\":\"2026-04-16T10:52:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/espeteros\\\/esp-160-lux-basic\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/espeteros\\\/esp-160-lux-basic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/espeteros\\\/esp-160-lux-basic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/353.500-ESP-160-Lux-Basic.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/353.500-ESP-160-Lux-Basic.png\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/catalogo\\\/espeteros\\\/esp-160-lux-basic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/pira-charcoal-ovens-company\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ESP 160 Lux Basic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"description\":\"Making charcoal ovens and barbecues since 1984.\",\"publisher\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\"},\"alternateName\":\"Pira Ovens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/piracharcoalovens.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Pira Charcoal Ovens and Barbecues\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Pira-Charcoal-Ovens\\\/274222069396877?fref=ts\",\"https:\\\/\\\/x.com\\\/Grill_PiraOvens\",\"https:\\\/\\\/www.instagram.com\\\/piraovens\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@pira_charcoal_ovens\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pira-charcoal-ovens-and-barbecues-s-l-\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCk_-TTJOHBVcGWsoz3hlSIg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESP 160 Lux Basic - Pira Charcoal Ovens and Barbecues","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/","og_locale":"es_ES","og_type":"article","og_title":"ESP 160 Lux Basic - Pira Charcoal Ovens and Barbecues","og_description":"Columna para sostener las rejas  Estante superior para mantener calientes las brochetas o los platos.  3 tipos de parrillas: de varillas, ranuradas y con soporte ajustable para brochetas.  Colector de grasa Inox con soporte para \"espetos\"  Interior de ladrillo refractario  Tolva de carb\u00f3n de hierro fundido  Cenicero  Patas ajustables de hierro  Atizador  Pinzas","og_url":"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/","og_site_name":"Pira Charcoal Ovens and Barbecues","article_publisher":"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","article_modified_time":"2026-04-16T10:52:50+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/353.500-ESP-160-Lux-Basic.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Grill_PiraOvens","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/","url":"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/","name":"ESP 160 Lux Basic - Pira Charcoal Ovens and Barbecues","isPartOf":{"@id":"https:\/\/piracharcoalovens.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/#primaryimage"},"image":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/#primaryimage"},"thumbnailUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/353.500-ESP-160-Lux-Basic.png","datePublished":"2026-02-17T15:40:55+00:00","dateModified":"2026-04-16T10:52:50+00:00","breadcrumb":{"@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/#primaryimage","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/353.500-ESP-160-Lux-Basic.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/353.500-ESP-160-Lux-Basic.png","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/piracharcoalovens.com\/es\/catalogo\/espeteros\/esp-160-lux-basic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/piracharcoalovens.com\/es\/pira-charcoal-ovens-company\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/piracharcoalovens.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"ESP 160 Lux Basic"}]},{"@type":"WebSite","@id":"https:\/\/piracharcoalovens.com\/#website","url":"https:\/\/piracharcoalovens.com\/","name":"Pira Charcoal Ovens and Barbecues","description":"Making charcoal ovens and barbecues since 1984.","publisher":{"@id":"https:\/\/piracharcoalovens.com\/#organization"},"alternateName":"Pira Ovens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/piracharcoalovens.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/piracharcoalovens.com\/#organization","name":"Pira Charcoal Ovens and Barbecues","url":"https:\/\/piracharcoalovens.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","width":512,"height":512,"caption":"Pira Charcoal Ovens and Barbecues"},"image":{"@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","https:\/\/x.com\/Grill_PiraOvens","https:\/\/www.instagram.com\/piraovens\/","https:\/\/www.tiktok.com\/@pira_charcoal_ovens","https:\/\/www.linkedin.com\/company\/pira-charcoal-ovens-and-barbecues-s-l-","https:\/\/www.youtube.com\/channel\/UCk_-TTJOHBVcGWsoz3hlSIg"]}]}},"_links":{"self":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product\/33439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/comments?post=33439"}],"version-history":[{"count":0,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product\/33439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/media\/33440"}],"wp:attachment":[{"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/media?parent=33439"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_brand?post=33439"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_cat?post=33439"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/es\/wp-json\/wp\/v2\/product_tag?post=33439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}