{"id":38941,"date":"2026-02-19T14:53:51","date_gmt":"2026-02-19T13:53:51","guid":{"rendered":"https:\/\/piracharcoalov.wpenginepowered.com\/catalog\/uncategorized\/taula-70-xl-silver\/"},"modified":"2026-04-21T18:08:33","modified_gmt":"2026-04-21T16:08:33","slug":"taula-70-xl-silver","status":"publish","type":"product","link":"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/","title":{"rendered":"Taula 70 XL Silver"},"content":{"rendered":"<p>A Pira Charcoal Ovens, cada forn s&#8217;acompanya d&#8217;una taula de disseny personalitzat. Les taules Pira s\u00f3n modernes, duraderes i capaces de suportar el pes del forn, alhora que s\u00f3n f\u00e0cils de maniobrar, independentment de la seva condici\u00f3 f\u00edsica. <\/p>\n<p>Cada taula t\u00e9 forats per fixar de manera segura les potes del forn, fent que les dues peces formin una unitat estable i evitant que es bolquin durant el moviment. Equipada amb quatre rodes resistents, la taula ofereix una mobilitat suau en qualsevol direcci\u00f3, amb rodes davanteres amb fre per bloquejar el forn al seu lloc un cop col\u00b7locat. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pira Charcoal Ovens, cada forn s&#8217;acompanya d&#8217;una taula de disseny personalitzat. Les taules Pira s\u00f3n modernes, duraderes i capaces de suportar el pes del forn, alhora que s\u00f3n f\u00e0cils de maniobrar, independentment de la seva condici\u00f3 f\u00edsica. Cada taula t\u00e9 forats per fixar de manera segura les potes del forn, fent que les dues [&hellip;]<\/p>\n","protected":false},"featured_media":1727,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[404],"product_tag":[],"class_list":["post-38941","product","type-product","status-publish","has-post-thumbnail","product_cat-accessoris","pa_accessory-type-taula-carbonera","pa_accessory-type-taules","pa_product-type-forns-de-brasa","pa_series-serie-silver","pa_size-70-xl","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taula 70 XL Silver - Pira Charcoal Ovens and Barbecues<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taula 70 XL Silver - Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"og:description\" content=\"A Pira Charcoal Ovens, cada forn s&#8217;acompanya d&#8217;una taula de disseny personalitzat. Les taules Pira s\u00f3n modernes, duraderes i capaces de suportar el pes del forn, alhora que s\u00f3n f\u00e0cils de maniobrar, independentment de la seva condici\u00f3 f\u00edsica. Cada taula t\u00e9 forats per fixar de manera segura les potes del forn, fent que les dues [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/\" \/>\n<meta property=\"og:site_name\" content=\"Pira Charcoal Ovens and Barbecues\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T16:08:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/table-70-XL-silver.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Grill_PiraOvens\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/ca\\\/cataleg\\\/accessoris\\\/taula-70-xl-silver\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/ca\\\/cataleg\\\/accessoris\\\/taula-70-xl-silver\\\/\",\"name\":\"Taula 70 XL Silver - Pira Charcoal Ovens and Barbecues\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/ca\\\/cataleg\\\/accessoris\\\/taula-70-xl-silver\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/ca\\\/cataleg\\\/accessoris\\\/taula-70-xl-silver\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/table-70-XL-silver.png\",\"datePublished\":\"2026-02-19T13:53:51+00:00\",\"dateModified\":\"2026-04-21T16:08:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/ca\\\/cataleg\\\/accessoris\\\/taula-70-xl-silver\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/piracharcoalovens.com\\\/ca\\\/cataleg\\\/accessoris\\\/taula-70-xl-silver\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/ca\\\/cataleg\\\/accessoris\\\/taula-70-xl-silver\\\/#primaryimage\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/table-70-XL-silver.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/table-70-XL-silver.png\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/ca\\\/cataleg\\\/accessoris\\\/taula-70-xl-silver\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/ca\\\/pira-charcoal-ovens-company-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\\\/\\\/piracharcoalovens.com\\\/ca\\\/botiga\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Taula 70 XL Silver\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#website\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"description\":\"Making charcoal ovens and barbecues since 1984.\",\"publisher\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\"},\"alternateName\":\"Pira Ovens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/piracharcoalovens.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#organization\",\"name\":\"Pira Charcoal Ovens and Barbecues\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"contentUrl\":\"https:\\\/\\\/piracharcoalovens.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-pira-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Pira Charcoal Ovens and Barbecues\"},\"image\":{\"@id\":\"https:\\\/\\\/piracharcoalovens.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Pira-Charcoal-Ovens\\\/274222069396877?fref=ts\",\"https:\\\/\\\/x.com\\\/Grill_PiraOvens\",\"https:\\\/\\\/www.instagram.com\\\/piraovens\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@pira_charcoal_ovens\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pira-charcoal-ovens-and-barbecues-s-l-\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCk_-TTJOHBVcGWsoz3hlSIg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taula 70 XL Silver - Pira Charcoal Ovens and Barbecues","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/","og_locale":"ca_ES","og_type":"article","og_title":"Taula 70 XL Silver - Pira Charcoal Ovens and Barbecues","og_description":"A Pira Charcoal Ovens, cada forn s&#8217;acompanya d&#8217;una taula de disseny personalitzat. Les taules Pira s\u00f3n modernes, duraderes i capaces de suportar el pes del forn, alhora que s\u00f3n f\u00e0cils de maniobrar, independentment de la seva condici\u00f3 f\u00edsica. Cada taula t\u00e9 forats per fixar de manera segura les potes del forn, fent que les dues [&hellip;]","og_url":"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/","og_site_name":"Pira Charcoal Ovens and Barbecues","article_publisher":"https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","article_modified_time":"2026-04-21T16:08:33+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/table-70-XL-silver.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Grill_PiraOvens","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/","url":"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/","name":"Taula 70 XL Silver - Pira Charcoal Ovens and Barbecues","isPartOf":{"@id":"https:\/\/piracharcoalovens.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/#primaryimage"},"image":{"@id":"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/#primaryimage"},"thumbnailUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/table-70-XL-silver.png","datePublished":"2026-02-19T13:53:51+00:00","dateModified":"2026-04-21T16:08:33+00:00","breadcrumb":{"@id":"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/#primaryimage","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/table-70-XL-silver.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/02\/table-70-XL-silver.png","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/piracharcoalovens.com\/ca\/cataleg\/accessoris\/taula-70-xl-silver\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/piracharcoalovens.com\/ca\/pira-charcoal-ovens-company-2\/"},{"@type":"ListItem","position":2,"name":"Botiga","item":"https:\/\/piracharcoalovens.com\/ca\/botiga\/"},{"@type":"ListItem","position":3,"name":"Taula 70 XL Silver"}]},{"@type":"WebSite","@id":"https:\/\/piracharcoalovens.com\/#website","url":"https:\/\/piracharcoalovens.com\/","name":"Pira Charcoal Ovens and Barbecues","description":"Making charcoal ovens and barbecues since 1984.","publisher":{"@id":"https:\/\/piracharcoalovens.com\/#organization"},"alternateName":"Pira Ovens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/piracharcoalovens.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/piracharcoalovens.com\/#organization","name":"Pira Charcoal Ovens and Barbecues","url":"https:\/\/piracharcoalovens.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/","url":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","contentUrl":"https:\/\/piracharcoalovens.com\/wp-content\/uploads\/2026\/03\/cropped-pira-favicon.png","width":512,"height":512,"caption":"Pira Charcoal Ovens and Barbecues"},"image":{"@id":"https:\/\/piracharcoalovens.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Pira-Charcoal-Ovens\/274222069396877?fref=ts","https:\/\/x.com\/Grill_PiraOvens","https:\/\/www.instagram.com\/piraovens\/","https:\/\/www.tiktok.com\/@pira_charcoal_ovens","https:\/\/www.linkedin.com\/company\/pira-charcoal-ovens-and-barbecues-s-l-","https:\/\/www.youtube.com\/channel\/UCk_-TTJOHBVcGWsoz3hlSIg"]}]}},"_links":{"self":[{"href":"https:\/\/piracharcoalovens.com\/ca\/wp-json\/wp\/v2\/product\/38941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piracharcoalovens.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piracharcoalovens.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/ca\/wp-json\/wp\/v2\/comments?post=38941"}],"version-history":[{"count":0,"href":"https:\/\/piracharcoalovens.com\/ca\/wp-json\/wp\/v2\/product\/38941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/piracharcoalovens.com\/ca\/wp-json\/wp\/v2\/media\/1727"}],"wp:attachment":[{"href":"https:\/\/piracharcoalovens.com\/ca\/wp-json\/wp\/v2\/media?parent=38941"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/ca\/wp-json\/wp\/v2\/product_brand?post=38941"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/ca\/wp-json\/wp\/v2\/product_cat?post=38941"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piracharcoalovens.com\/ca\/wp-json\/wp\/v2\/product_tag?post=38941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}